{"id":6553,"date":"2024-05-24T19:00:00","date_gmt":"2024-05-24T22:00:00","guid":{"rendered":"https:\/\/sgvaimudar.com.br\/?p=6553"},"modified":"2024-05-24T10:30:35","modified_gmt":"2024-05-24T13:30:35","slug":"defesa-civil-ensina-primeiros-socorros-em-escola-no-salgueiro","status":"publish","type":"post","link":"https:\/\/sgvaimudar.com.br\/index.php\/2024\/05\/24\/defesa-civil-ensina-primeiros-socorros-em-escola-no-salgueiro\/","title":{"rendered":"Defesa Civil ensina primeiros socorros em escola no Salgueiro\u00a0"},"content":{"rendered":"\n<p><em>Novidade \u00e9 um jogo de tabuleiro para que crian\u00e7as entendam trabalho dos agentes\u00a0<\/em><\/p>\n\n\n\n<p>Agentes da Defesa Civil de S\u00e3o Gon\u00e7alo estiveram na Escola Estadual Municipalizada Professora Niuma Goulart Brand\u00e3o, no bairro do Salgueiro, para realizar uma palestra sobre primeiros socorros para pais, alunos e professores. A novidade ficou por conta de um jogo de tabuleiro que faz com que as crian\u00e7as entendam os cen\u00e1rios de risco e cat\u00e1strofes e a import\u00e2ncia do trabalho da Defesa Civil no munic\u00edpio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2024\/05\/unnamed-38-768x1024.jpg\" alt=\"\" class=\"wp-image-6556\" srcset=\"https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2024\/05\/unnamed-38-768x1024.jpg 768w, https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2024\/05\/unnamed-38-225x300.jpg 225w, https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2024\/05\/unnamed-38-1152x1536.jpg 1152w, https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2024\/05\/unnamed-38.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Na escola, os participantes receberam informa\u00e7\u00f5es sobre massagem card\u00edaca, manobras de desengasgo, transporte de v\u00edtimas com o uso de pranchas r\u00edgidas e outras no\u00e7\u00f5es. Al\u00e9m disso, foram expostos os equipamentos e materiais utilizados pela Defesa Civil e as crian\u00e7as puderam vestir capas de inc\u00eandio, capacetes e entender a import\u00e2ncia desses itens nos salvamentos.<\/p>\n\n\n\n<p>&#8220;A finalidade \u00e9 levar os conhecimentos t\u00e9cnicos para alunos, professores e respons\u00e1veis. Entendemos que, dessa forma, consolidamos mais ainda os conhecimentos, j\u00e1 que eles podem conversar entre si. Queremos levar esse projeto para outras escolas e locais de reuni\u00e3o para que mais pessoas saibam e repassem as informa\u00e7\u00f5es. Esclarecemos sobre a import\u00e2ncia do nosso servi\u00e7o, dos bombeiros e do SAMU, al\u00e9m dos telefones para que as crian\u00e7as saibam tamb\u00e9m como pedir ajuda. Dessa forma, o p\u00fablico gon\u00e7alense ganha cada vez mais&#8221;, disse o major Felipe Assun\u00e7\u00e3o, subsecret\u00e1rio de Defesa Civil.<\/p>\n\n\n\n<p>A Defesa Civil de S\u00e3o Gon\u00e7alo realiza constantemente eventos de capacita\u00e7\u00e3o e treinamentos para seus servidores e tamb\u00e9m junto \u00e0 popula\u00e7\u00e3o, para enfrentamento dos per\u00edodos de chuvas e preven\u00e7\u00e3o de desastres naturais, como cursos para volunt\u00e1rios, Defesa Civil nas Pra\u00e7as e outros.<\/p>\n\n\n\n<p>Ainda neste m\u00eas, a Defesa Civil ir\u00e1 realizar mais uma palestra de primeiros socorros, no dia 28, na Associa\u00e7\u00e3o de Moradores do Jardim Catarina. Al\u00e9m disso, neste s\u00e1bado (25), \u00e0s 9h, ser\u00e1 feito um exerc\u00edcio de desocupa\u00e7\u00e3o na sirene do bairro Porto Novo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novidade \u00e9 um jogo de tabuleiro para que crian\u00e7as entendam trabalho dos agentes\u00a0 Agentes da Defesa Civil de S\u00e3o Gon\u00e7alo&hellip;<\/p>\n","protected":false},"author":5,"featured_media":6555,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-6553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sao-goncalo"],"_links":{"self":[{"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6553"}],"version-history":[{"count":1,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6553\/revisions"}],"predecessor-version":[{"id":6557,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6553\/revisions\/6557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/media\/6555"}],"wp:attachment":[{"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}