{"id":44210,"date":"2026-07-15T11:00:00","date_gmt":"2026-07-15T14:00:00","guid":{"rendered":"https:\/\/sgvaimudar.com.br\/?p=44210"},"modified":"2026-07-15T08:57:53","modified_gmt":"2026-07-15T11:57:53","slug":"capitao-nelson-prestigia-homenagem-a-profissionais-da-educacao-por-conquista-nacional","status":"publish","type":"post","link":"https:\/\/sgvaimudar.com.br\/index.php\/2026\/07\/15\/capitao-nelson-prestigia-homenagem-a-profissionais-da-educacao-por-conquista-nacional\/","title":{"rendered":"Capit\u00e3o Nelson prestigia homenagem a profissionais da Educa\u00e7\u00e3o por conquista nacional"},"content":{"rendered":"\n<p><em>Chefe do Executivo gon\u00e7alense participou da men\u00e7\u00e3o honrosa por projeto de alimenta\u00e7\u00e3o escolar<\/em><\/p>\n\n\n\n<p>O prefeito Capit\u00e3o Nelson homenageou, nesta ter\u00e7a-feira (14), os profissionais da Escola Estadual Municipalizada Itaitindiba, em Santa Izabel, e as nutricionistas da Subsecretaria de Alimenta\u00e7\u00e3o Escolar pelo pr\u00eamio conquistado na 7\u00aa Jornada de Educa\u00e7\u00e3o Alimentar e Nutricional do Fundo Nacional de Desenvolvimento da Educa\u00e7\u00e3o (FNDE), em Bras\u00edlia. A cerim\u00f4nia, realizada no audit\u00f3rio da Secretaria de Educa\u00e7\u00e3o, contou com a entrega de mo\u00e7\u00f5es de aplausos em reconhecimento ao trabalho desenvolvido pelas equipes.<\/p>\n\n\n\n<p>A Escola Estadual Municipalizada Itaitindiba foi premiada com R$ 10 mil pelo projeto da Feira da Agricultura Familiar, iniciativa que se destacou nacionalmente por incentivar a educa\u00e7\u00e3o alimentar e valorizar a produ\u00e7\u00e3o local. O reconhecimento tamb\u00e9m contemplou a atua\u00e7\u00e3o das nutricionistas da rede municipal, que contribu\u00edram para o sucesso da proposta.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-2-8-1024x683.jpg\" alt=\"\" class=\"wp-image-44214\" srcset=\"https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-2-8-1024x683.jpg 1024w, https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-2-8-300x200.jpg 300w, https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-2-8-768x512.jpg 768w, https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-2-8-1536x1024.jpg 1536w, https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-2-8-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u201c\u00c9 uma satisfa\u00e7\u00e3o estar aqui. N\u00f3s sabemos que a meta principal da escola \u00e9 o ensino pedag\u00f3gico, mas sei tamb\u00e9m da necessidade da nossa popula\u00e7\u00e3o. N\u00f3s observamos em governos anteriores muitos problemas envolvendo a merenda escolar e n\u00f3s colocamos um ponto final nesta hist\u00f3ria. Eu sempre refor\u00e7o o quanto \u00e9 importante a alimenta\u00e7\u00e3o das crian\u00e7as, para que elas possam adquirir o conhecimento bem alimentadas\u201d, disse o prefeito.&nbsp;<\/p>\n\n\n\n<p>A 7\u00aa edi\u00e7\u00e3o da jornada contou com 2800 escolas inscritas de todo o pa\u00eds. Foram selecionadas 20 escolas com os melhores relatos de atividades realizadas. A Escola Estadual Municipalizada Itaitindiba foi a \u00fanica escola do Rio de Janeiro dentre as selecionadas, com a atividade \u201cFeirinha na escola: sabores da agricultura\u201d, voltada para o incentivo a agricultura familiar do munic\u00edpio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-4-8-1024x683.jpg\" alt=\"\" class=\"wp-image-44216\" srcset=\"https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-4-8-1024x683.jpg 1024w, https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-4-8-300x200.jpg 300w, https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-4-8-768x512.jpg 768w, https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-4-8-1536x1024.jpg 1536w, https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-4-8-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u201c\u00c9 uma felicidade muito grande para n\u00f3s da Secretaria de Educa\u00e7\u00e3o sabermos que o nosso projeto em Itaitindiba foi premiado, que a nossa alimenta\u00e7\u00e3o escolar est\u00e1 sendo vista e valorizada. N\u00f3s precisamos desse apoio dos merendeiros e nutricionistas, toda a equipe \u00e9 importante para que o aluno receba a merenda escolar de qualidade. \u00c9 um cuidado e um carinho que faz com que eles estejam nutridos para aprenderem melhor em sala de aula\u201d, afirmou o secret\u00e1rio de Educa\u00e7\u00e3o, Mauricio Nascimento.<\/p>\n\n\n\n<p>A diretora da escola, Adriana Pereira, entende que a alimenta\u00e7\u00e3o escolar de qualidade depende de v\u00e1rios fatores. \u201cEu acredito que esse pr\u00eamio \u00e9 um resultado de v\u00e1rios trabalhos, temos a Secretaria de Educa\u00e7\u00e3o, a Prefeitura de S\u00e3o Gon\u00e7alo, que mudou a cara da alimenta\u00e7\u00e3o escolar, temos a escola, as merendeiras, os alunos. Todos juntos trabalhando em prol da Educa\u00e7\u00e3o. A alimenta\u00e7\u00e3o n\u00e3o \u00e9 s\u00f3 servir uma refei\u00e7\u00e3o, ela muda o f\u00edsico, o cognitivo, o social, \u00e9 uma oportunidade de interagir no momento do almo\u00e7o, ent\u00e3o \u00e9 uma parte muito importante da escola\u201d.<\/p>\n\n\n\n<p><em>Fotos: Jonnathan Smith<\/em><\/p>\n\n\n\n<p><strong><em>Passe sua informa\u00e7\u00e3o pelo nosso WhatsApp: (21) <\/em><\/strong><strong><em>99744 5345<\/em><\/strong><strong><em><\/em><\/strong><\/p>\n\n\n\n<p><strong><em>S\u00e3o Gon\u00e7alo Vai Mudar: Not\u00edcias de S\u00e3o Gon\u00e7alo e toda regi\u00e3o.<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1280\" style=\"aspect-ratio: 720 \/ 1280;\" width=\"720\" controls src=\"https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/01\/NoticiaUrgete.logoSGVM.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Chefe do Executivo gon\u00e7alense participou da men\u00e7\u00e3o honrosa por projeto de alimenta\u00e7\u00e3o escolar O prefeito Capit\u00e3o Nelson homenageou, nesta ter\u00e7a-feira&hellip;<\/p>\n","protected":false},"author":5,"featured_media":44213,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/sgvaimudar.com.br\/wp-content\/uploads\/2026\/07\/unnamed-3-7-scaled.jpg","fifu_image_alt":"","footnotes":""},"categories":[3],"tags":[203,1913,250,240,47,75],"class_list":["post-44210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sao-goncalo","tag-capitao","tag-conquista","tag-educacao","tag-nelson","tag-rj","tag-sao-goncalo"],"_links":{"self":[{"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=44210"}],"version-history":[{"count":2,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44210\/revisions"}],"predecessor-version":[{"id":44217,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44210\/revisions\/44217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/media\/44213"}],"wp:attachment":[{"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=44210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=44210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sgvaimudar.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=44210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}